{"id":325,"date":"2014-03-06T11:48:13","date_gmt":"2014-03-06T10:48:13","guid":{"rendered":"http:\/\/www.kulturstarter.de\/?p=325"},"modified":"2014-03-06T11:48:13","modified_gmt":"2014-03-06T10:48:13","slug":"theater-ag","status":"publish","type":"post","link":"https:\/\/www.lkjbw.de\/blog\/2014\/03\/theater-ag\/","title":{"rendered":"Theater-AG"},"content":{"rendered":"<p>Lau<a href=\"\/blog\/wp-content\/uploads\/2014\/03\/1913340_530998063682464_94117964_o.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-326 colorbox-325\" style=\"margin: 10px;\" alt=\"1913340_530998063682464_94117964_o\" src=\"\/blog\/wp-content\/uploads\/2014\/03\/1913340_530998063682464_94117964_o-300x162.jpg\" width=\"300\" height=\"162\" \/><\/a>ra und Annika vom Kreisgymnasium Riedlingen leiten an ihrer Schule die Theater-AG. Sie schreiben die St\u00fccke selber, organisieren die Requisiten und planen die Proben. Da sie schon seit der Grundschule Theater spielen und an ihrer Schule keine AG angeboten wurde, haben sie sich entschlossen, diese als ihr Projekt selber zu gr\u00fcnden. Seitdem haben sie schon mehrere St\u00fccke aufgef\u00fchrt, die sie selbst geschrieben oder bearbeitet haben und planen, dieses Jahr noch eine Kriminalkom\u00f6die aufzuf\u00fchren.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laura und Annika vom Kreisgymnasium Riedlingen leiten an ihrer Schule die Theater-AG. Sie schreiben die St\u00fccke selber, organisieren die Requisiten und planen die Proben. Da sie schon seit der Grundschule Theater spielen und an ihrer Schule keine AG angeboten wurde, haben sie sich entschlossen, diese als ihr Projekt selber zu gr\u00fcnden. Seitdem haben sie schon&#8230; <a class=\"moretag\" href=\"https:\/\/www.lkjbw.de\/blog\/2014\/03\/theater-ag\/\"> weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":19,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/325"}],"collection":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/comments?post=325"}],"version-history":[{"count":0,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/325\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media?parent=325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/categories?post=325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/tags?post=325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}