{"id":3630,"date":"2015-12-01T15:16:05","date_gmt":"2015-12-01T13:16:05","guid":{"rendered":"https:\/\/www.lkjbw.de\/blog\/?p=3630"},"modified":"2017-10-02T14:35:22","modified_gmt":"2017-10-02T12:35:22","slug":"winterhaldenschule-sindelfingen","status":"publish","type":"post","link":"https:\/\/www.lkjbw.de\/blog\/2015\/12\/winterhaldenschule-sindelfingen\/","title":{"rendered":"Winterhaldenschule Sindelfingen"},"content":{"rendered":"<p><img loading=\"lazy\" width=\"298\" height=\"300\" class=\"size-medium wp-image-3631 alignleft colorbox-3630\" style=\"font-family: Georgia, 'Times New Roman', 'Bitstream Charter', Times, serif; font-size: 16px;\" src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Sindelfingen-298x300.jpg\" alt=\"\" srcset=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Sindelfingen-298x300.jpg 298w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Sindelfingen-150x150.jpg 150w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Sindelfingen.jpg 768w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Sindelfingen-174x175.jpg 174w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Sindelfingen-125x125.jpg 125w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Sindelfingen-298x300@2x.jpg 596w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Sindelfingen-150x150@2x.jpg 300w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Sindelfingen-174x175@2x.jpg 348w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Sindelfingen-125x125@2x.jpg 250w\" sizes=\"(max-width: 298px) 100vw, 298px\" \/>Im Vorfeld wurde der Workshopinhalt mit dem betreuenden Klassenlehrer abgesprochen. Die Klasse hatte schon kurz nach den Herbstferien begonnen nach dem Thema f\u00fcr eine H\u00f6rspielgeschichte zu suchen. Herausgekommen war ein erster Entwurf f\u00fcr eine Weihnachtsgeschichte, an der die Sch\u00fcler noch in der Woche vor dem Workshop weiter gearbeitet hatten. Die Geschichte stand etwa zur H\u00e4lfte, dazu gekommen waren noch einige Charaktere, die die Sch\u00fcler teilweise f\u00fcr die Geschichte, teilweise aber auch unabh\u00e4ngig davon entwickelt hatten.<\/p>\n<p>Am Anfang bestand die Schwierigkeit, dass die Sch\u00fcler auf einen Gro\u00dfteil der Charaktere verzichten mussten, weil sie in der Weihnachtsgeschichte nicht unterzubringen waren, vielmehr dort f\u00fcr Konfusion und Un\u00fcbersichtlichkeit gesorgt h\u00e4tten. Au\u00dferdem w\u00e4re die Geschichte dann viel zu lang geworden und sehr sicher im Rahmen des Workshops nicht zu bew\u00e4ltigen gewesen.<\/p>\n<p>Gemeinsam wurde die Geschichte auf das urspr\u00fcngliche Konzept reduziert und weiter geschrieben. Ein Teil der Gruppe ging schon gleich am Anfang auf Ger\u00e4uschejagd, denn welche Ger\u00e4usche f\u00fcr das H\u00f6rspiel notwendig waren, war nach dem Zuendeerz\u00e4hlen des Plots klar. Der zweite Teil der Gruppe machte sich am Whiteboard daran, die Geschichte in Dialoge umzuformen. Klar war schnell, dass ein Erz\u00e4hler her musste. Zudem wurden Rollen festgelegt, so dass jeder mit einer Sprechrolle in der Geschichte vertreten war. Die Dialogarbeit hat wunderbar geklappt. Die Sch\u00fcler beteiligten sich aktiv und mit sehr konstruktiven Vorschl\u00e4gen.<\/p>\n<p>Der gr\u00f6\u00dfte Teil der Ger\u00e4usche war bis Nachmittag aufgenommen. Ein paar wenige wurden im Lauf des zweiten Tages eingefangen. Einen Teil davon schnitten einige Teilnehmer selber mit Audacity. Die Sch\u00fcler legten bei den Ger\u00e4uschen richtig Eifer an den Tag. Sie waren stolz darauf auszuprobieren, welches T\u00fcrger\u00e4usch aus der Schule denn zu der Geschichte passen w\u00fcrde.<\/p>\n<p>Vor den Sprechaufnahmen am zweiten Tag nahmen wir uns viel Zeit, die Rollen einzu\u00fcben und auch an der Rollengestaltung zu arbeiten. Anschlie\u00dfend begannen die Aufnahmen und es ist ein sch\u00f6nes 10-min\u00fctiges H\u00f6rst\u00fcck zur Weihnachtszeit entstanden.<\/p>\n<p>&nbsp;<\/p>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n<audio class=\"wp-audio-shortcode\" id=\"audio-3630-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Weihnachtsgeschichte.mp3?_=1\" \/><a href=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Weihnachtsgeschichte.mp3\">https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/09\/Weihnachtsgeschichte.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>Im Vorfeld wurde der Workshopinhalt mit dem betreuenden Klassenlehrer abgesprochen. Die Klasse hatte schon kurz nach den Herbstferien begonnen nach dem Thema f\u00fcr eine H\u00f6rspielgeschichte zu suchen. Herausgekommen war ein erster Entwurf f\u00fcr eine Weihnachtsgeschichte, an der die Sch\u00fcler noch in der Woche vor dem Workshop weiter gearbeitet hatten. Die Geschichte stand etwa zur H\u00e4lfte,&#8230; <a class=\"moretag\" href=\"https:\/\/www.lkjbw.de\/blog\/2015\/12\/winterhaldenschule-sindelfingen\/\"> weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":11,"featured_media":3631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/3630"}],"collection":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/comments?post=3630"}],"version-history":[{"count":2,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/3630\/revisions"}],"predecessor-version":[{"id":3667,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/3630\/revisions\/3667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media\/3631"}],"wp:attachment":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media?parent=3630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/categories?post=3630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/tags?post=3630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}