{"id":3784,"date":"2017-10-19T17:02:21","date_gmt":"2017-10-19T15:02:21","guid":{"rendered":"https:\/\/www.lkjbw.de\/blog\/?p=3784"},"modified":"2017-12-19T17:21:02","modified_gmt":"2017-12-19T15:21:02","slug":"johannes-wagner-schule-nuertingen","status":"publish","type":"post","link":"https:\/\/www.lkjbw.de\/blog\/2017\/10\/johannes-wagner-schule-nuertingen\/","title":{"rendered":"Johannes-Wagner-Schule N\u00fcrtingen"},"content":{"rendered":"<img loading=\"lazy\" width=\"300\" height=\"201\" class=\"size-medium wp-image-3785 alignleft colorbox-3784\" src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/12\/N\u00fcrtingen-300x201.jpg\" alt=\"\" srcset=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/12\/N\u00fcrtingen-300x201.jpg 300w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/12\/N\u00fcrtingen-768x516.jpg 768w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/12\/N\u00fcrtingen-345x230.jpg 345w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/12\/N\u00fcrtingen-250x168.jpg 250w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/12\/N\u00fcrtingen.jpg 800w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/12\/N\u00fcrtingen-300x201@2x.jpg 600w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/12\/N\u00fcrtingen-345x230@2x.jpg 690w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2017\/12\/N\u00fcrtingen-250x168@2x.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\n<p>Zw\u00f6lf Sch\u00fcler*innen der Johannes-Wagner-Schule, SBBZ mit dem F\u00f6rderschwerpunkt H\u00f6ren und Sprache, in N\u00fcrtingen nahmen Mitte Oktober an dem Medienprojekt \u201eH\u00f6r- und Sehst\u00fccke\u201c der Landesvereinigung Kulturelle Jugendbildung (LKJ) teil. Bereits im Vorhinein hatte sich die Klasse dazu entschieden eine Videoreportage zum Thema \u201eStreit schlichten\u201c zu drehen, deshalb konnten sie relativ fr\u00fch mit dem Dreh beginnen. Bei der Kennenlernrunde stellte sich heraus, dass bereits zwei Sch\u00fcler der Klasse Streitschlichter waren, allerdings hatten sie die Ausbildung erst frisch abgeschlossen und hatten dadurch noch keine Erfahrungen von denen sie in einem Interview h\u00e4tten berichten k\u00f6nnen.<\/p>\n<p>Die Dreharbeiten begannen mit einem simulierten Streitschlichtungsgespr\u00e4ch, bei dem sich die Sch\u00fcler*innen sehr gut in die Szene hineinversetzten. Neben den gespielten Szenen f\u00fchrten sie auch Interviews mit erfahreneren Streitschlichter*innen und Lehrerinnen, stellten die Regeln einer Streitschlichtung auf Plakaten visuell dar, interviewten sich gegenseitig zum Thema Streit und produzierten An- und Abspann. Alles in allem arbeiteten die Teams schnell und oft komplett selbstst\u00e4ndig, womit sie auch ihre Lehrerin beeindruckten.<\/p>\n<div class=\"lyte-wrapper\" style=\"width:560px;max-width:100%;margin:5px;\"><div class=\"lyMe\" id=\"WYL_QZcvEpkxxMA\"><div id=\"lyte_QZcvEpkxxMA\" data-src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=%2F%2Fi.ytimg.com%2Fvi%2FQZcvEpkxxMA%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\"><\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/QZcvEpkxxMA\"><img class=\"colorbox-3784\"  src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FQZcvEpkxxMA%2F0.jpg\" alt=\"\" width=\"560\" height=\"295\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:560px;margin:5px;\"><br\/><span class=\"lyte_disclaimer\">Hinweis: Wenn Sie das Video starten werden Informationen an YouTube gesendet und gespeichert. Bitte beachten Sie unsere Hinweise zum <a href=\"\/blog\/datenschutz\/\">Datenschutz<\/a>.<\/span><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zw\u00f6lf Sch\u00fcler*innen der Johannes-Wagner-Schule, SBBZ mit dem F\u00f6rderschwerpunkt H\u00f6ren und Sprache, in N\u00fcrtingen nahmen Mitte Oktober an dem Medienprojekt \u201eH\u00f6r- und Sehst\u00fccke\u201c der Landesvereinigung Kulturelle Jugendbildung (LKJ) teil. Bereits im Vorhinein hatte sich die Klasse dazu entschieden eine Videoreportage zum Thema \u201eStreit schlichten\u201c zu drehen, deshalb konnten sie relativ fr\u00fch mit dem Dreh beginnen. Bei&#8230; <a class=\"moretag\" href=\"https:\/\/www.lkjbw.de\/blog\/2017\/10\/johannes-wagner-schule-nuertingen\/\"> weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":11,"featured_media":3785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/3784"}],"collection":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/comments?post=3784"}],"version-history":[{"count":2,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/3784\/revisions"}],"predecessor-version":[{"id":3787,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/3784\/revisions\/3787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media\/3785"}],"wp:attachment":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media?parent=3784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/categories?post=3784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/tags?post=3784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}