{"id":5844,"date":"2021-04-26T10:41:48","date_gmt":"2021-04-26T08:41:48","guid":{"rendered":"https:\/\/www.lkjbw.de\/blog\/?p=5844"},"modified":"2021-04-26T10:41:48","modified_gmt":"2021-04-26T08:41:48","slug":"klimazeitschrift-am-markgraf-ludwig-gymnasium-baden-baden","status":"publish","type":"post","link":"https:\/\/www.lkjbw.de\/blog\/2021\/04\/klimazeitschrift-am-markgraf-ludwig-gymnasium-baden-baden\/","title":{"rendered":"Klimazeitschrift am Markgraf-Ludwig Gymnasium Baden-Baden"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-medium\"><img loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2021\/04\/Klimazeitschrift-300x300.jpg\" alt=\"\" class=\"wp-image-5845 colorbox-5844\" srcset=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2021\/04\/Klimazeitschrift-150x150@2x.jpg 300w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2021\/04\/Klimazeitschrift-150x150.jpg 150w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2021\/04\/Klimazeitschrift-175x175.jpg 175w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2021\/04\/Klimazeitschrift-125x125.jpg 125w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2021\/04\/Klimazeitschrift.jpg 656w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2021\/04\/Klimazeitschrift-300x300@2x.jpg 600w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2021\/04\/Klimazeitschrift-175x175@2x.jpg 350w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2021\/04\/Klimazeitschrift-125x125@2x.jpg 250w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>Als aktives Mitglied der Fridays For Future-Bewegung machte es sich die Kulturstarterin Pauline zu ihrem Projekt am Markgraf-Ludwig-Gymnasium Baden-Baden f\u00fcr den Klima- und Umweltschutz zu werben. Urspr\u00fcngliche Projektideen wie ein Kreidewettbewerb in der Innenstadt wurden leider durch Abstandsregelungen und weitere Einschr\u00e4nkungen durchkreuzt. Das schien sie jedoch nicht zu bremsen \u2013 im Gegenteil: Ganz unter dem Motto \u201eF\u00fcr die Klimakrise gibt es keine Impfung!\u201c brachte sie die Idee einer Klimazeitschrift f\u00fcr ihre Mitsch\u00fcler*innen auf den Weg. Daf\u00fcr gr\u00fcndete die Kulturstarterin ein Team an ihrer Schule und die Recherche-, sowie Redaktionsarbeiten konnten beginnen! Mehr als 20 motivierte Sch\u00fcler*innen reichten Texte zu Themen wie dem \u00d6kologischer Fu\u00dfabdruck, Klimal\u00fcgen bis hin zu Tipps f\u00fcr einen nachhaltigeren Alltag ein. So entstand nach und nach ein beeindruckendes Printmedium mit 28 wundersch\u00f6n und professionell gestalteten Seiten.<br>Damit diese Zeitung auch wirklich in einer gro\u00dfen St\u00fcckzahl gedruckt werden kann und viele Menschen erreicht, bewarb sich Pauline mit ihrem Projekt beim F\u00f6rderprogramm \u201ePUSH DICH!\u201c der Baden-W\u00fcrttemberg Stiftung, das Projektb\u00fcro \u00fcbernimmt die LKJ.<br>Der Jury gefiel das Projekt sehr gut und sie sicherte daher eine finanzielle Unterst\u00fctzung der Druckkosten zu. Das Ergebnis kann sich wirklich sehen lassen und auch der jungen Projektleiterin ist der Stolz auf das beeindruckende Ergebnis anzusehen. Auch wir freuen uns sehr, wie toll hier Kultur, Engagement, Zusammenarbeit und Umweltschutz an der Schule umgesetzt wurden. Die Klimazeitschrift tr\u00e4gt dazu bei gemeinsam unsere Welt etwas sch\u00f6ner zu machen und die Zukunft mitzugestalten \u2013 und das nicht erst irgendwann, sondern jetzt!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als aktives Mitglied der Fridays For Future-Bewegung machte es sich die Kulturstarterin Pauline zu ihrem Projekt am Markgraf-Ludwig-Gymnasium Baden-Baden f\u00fcr den Klima- und Umweltschutz zu werben. Urspr\u00fcngliche Projektideen wie ein Kreidewettbewerb in der Innenstadt wurden leider durch Abstandsregelungen und weitere Einschr\u00e4nkungen durchkreuzt. Das schien sie jedoch nicht zu bremsen \u2013 im Gegenteil: Ganz unter dem&#8230; <a class=\"moretag\" href=\"https:\/\/www.lkjbw.de\/blog\/2021\/04\/klimazeitschrift-am-markgraf-ludwig-gymnasium-baden-baden\/\"> weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":11,"featured_media":5845,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"_links":{"self":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/5844"}],"collection":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/comments?post=5844"}],"version-history":[{"count":2,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/5844\/revisions"}],"predecessor-version":[{"id":5847,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/5844\/revisions\/5847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media\/5845"}],"wp:attachment":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media?parent=5844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/categories?post=5844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/tags?post=5844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}