{"id":7803,"date":"2023-06-27T15:00:23","date_gmt":"2023-06-27T13:00:23","guid":{"rendered":"https:\/\/www.lkjbw.de\/blog\/?p=7803"},"modified":"2024-07-01T12:55:48","modified_gmt":"2024-07-01T10:55:48","slug":"landesweiter-schuelerradiotag-am-29-september-2023","status":"publish","type":"post","link":"https:\/\/www.lkjbw.de\/blog\/2023\/06\/landesweiter-schuelerradiotag-am-29-september-2023\/","title":{"rendered":"Landesweiter Sch\u00fclerRadioTag am 29. September 2023"},"content":{"rendered":"\n<p>Am 29. September 2023 \u00fcbernehmen wir wieder f\u00fcr einen Tag die Hochschule der Medien und machen ganz viel Audio &#8211; Denn die Landesvereinigung Kulturelle Jugendbildung (LKJ) Baden-W\u00fcrttemberg e.V. l\u00e4d wieder radiointeressierte Sch\u00fcler*innen und deren Lehrkr\u00e4fte aus ganz Baden-W\u00fcrttemberg zum 18.&nbsp; landesweiten Sch\u00fclerRadioTag an der Hochschule der Medien in Stuttgart-Vaihingen ein.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-medium\"><img loading=\"lazy\" width=\"200\" height=\"300\" src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_134_credit_marcschiele-200x300.jpg\" alt=\"\" class=\"wp-image-7807 colorbox-7803\" srcset=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_134_credit_marcschiele-200x300.jpg 200w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_134_credit_marcschiele-683x1024.jpg 683w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_134_credit_marcschiele-1024x1536.jpg 1024w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_134_credit_marcschiele-1365x2048.jpg 1365w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_134_credit_marcschiele-117x175.jpg 117w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_134_credit_marcschiele-scaled.jpg 1707w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_134_credit_marcschiele-200x300@2x.jpg 400w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_134_credit_marcschiele-683x1024@2x.jpg 1366w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/figure><\/div>\n\n\n<p>In insgesamt 13 verschiedenen Workshops gibt es die Gelegenheit, alles rund um das Medium Radio zu lernen und nat\u00fcrlich auch selbst aktiv zu werden. Die Teilnehmenden machen Umfragen, f\u00fchren Interviews oder produzieren Podcasts, Sounds oder H\u00f6rspiele. Gleichzeitig erhalten sie Informationen zu vielen verschiedenen Medienberufen und k\u00f6nnen sich mit anderen Jugendlichen sowie Radioprofis austauschen. Mit dabei auch wieder unser DJ-Workshop, Moderation, Fake News und auch die eigene Life Sendung. Lehrer*innen erfahren in einem eigenen Workshop, wie sie Audioarbeit in ihrer Schule und im Unterricht vielseitig einsetzen k\u00f6nnen, welche M\u00f6glichkeiten und Chancen das Medium bietet und bekommen Informationen \u00fcber aktuelle Wettbewerbe, F\u00f6rdermittel und medienp\u00e4dagogische Angebote.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-medium\"><img loading=\"lazy\" width=\"300\" height=\"200\" src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_25_credit_marcschiele-300x200.jpg\" alt=\"\" class=\"wp-image-7808 colorbox-7803\" srcset=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_25_credit_marcschiele-300x200.jpg 300w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_25_credit_marcschiele-1024x683.jpg 1024w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_25_credit_marcschiele-1536x1024.jpg 1536w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_25_credit_marcschiele-2048x1365.jpg 2048w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_25_credit_marcschiele-345x230.jpg 345w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_25_credit_marcschiele-250x167.jpg 250w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_25_credit_marcschiele-300x200@2x.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n<p>Das Angebot richtet sich sowohl an Neulinge, die eine Radio-AG an ihrer Schule etablieren oder Audioprojekte ansto\u00dfen wollen, als auch an Jugendliche mit Erfahrung, die ihr Know-how ausbauen und mit wertvollen Tipps von Expert*innen erweitern wollen. Der Sch\u00fclerRadioTag wird gef\u00f6rdert von der <a rel=\"noreferrer noopener\" href=\"https:\/\/www.lfk.de\/\" target=\"_blank\">LFK, der Medienanstalt f\u00fcr Baden-W\u00fcrttemberg<\/a>. Kooperationspartner sind die Hochschule der Medien Stuttgart, der Radiosender bigFM, das Hochschulradio HORADS 88,6 und das POP-B\u00fcro Region Stuttgart.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-medium\"><img loading=\"lazy\" width=\"300\" height=\"200\" src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_61_credit_marcschiele-300x200.jpg\" alt=\"\" class=\"wp-image-7809 colorbox-7803\" srcset=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_61_credit_marcschiele-300x200.jpg 300w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_61_credit_marcschiele-1024x683.jpg 1024w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_61_credit_marcschiele-1536x1024.jpg 1536w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_61_credit_marcschiele-2048x1365.jpg 2048w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_61_credit_marcschiele-345x230.jpg 345w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_61_credit_marcschiele-250x167.jpg 250w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2023\/06\/schuelerradiotag_2022_61_credit_marcschiele-300x200@2x.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n<p>Die Teilnahme am Sch\u00fclerRadioTag ist kostenfrei! Gruppen und Einzelteilnehmer*innen k\u00f6nnen sich ab jetzt und bis sp\u00e4testens zum 22. September 2022 anmelden, wobei eine schnelle Anmeldung aufgrund der begrenzten und begehrten Pl\u00e4tze sehr ratsam ist. Weitere Informationen zum Sch\u00fclerRadioTag, das diesj\u00e4hrige Programm und den Anmeldebogen gibt es unter: <a rel=\"noreferrer noopener\" href=\"https:\/\/www.lkjbw.de\/schule-kultur-medien\/schuelerradiotag\" target=\"_blank\">www.lkjbw.de\/schuelerradiotag<\/a>. Beispiele zum Nachh\u00f6ren vom letzten Sch\u00fclerRadioTag gibt es <a rel=\"noreferrer noopener\" href=\"https:\/\/www.lkjbw.de\/blog\/2022\/09\/rueckblick-17-schuelerradiotag-am-30-09-2022\/\" target=\"_blank\">hier.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 29. September 2023 \u00fcbernehmen wir wieder f\u00fcr einen Tag die Hochschule der Medien und machen ganz viel Audio &#8211; Denn die Landesvereinigung Kulturelle Jugendbildung (LKJ) Baden-W\u00fcrttemberg e.V. l\u00e4d wieder radiointeressierte Sch\u00fcler*innen und deren Lehrkr\u00e4fte aus ganz Baden-W\u00fcrttemberg zum 18.&nbsp; landesweiten Sch\u00fclerRadioTag an der Hochschule der Medien in Stuttgart-Vaihingen ein. In insgesamt 13 verschiedenen Workshops&#8230; <a class=\"moretag\" href=\"https:\/\/www.lkjbw.de\/blog\/2023\/06\/landesweiter-schuelerradiotag-am-29-september-2023\/\"> weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":16,"featured_media":7805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/7803"}],"collection":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/comments?post=7803"}],"version-history":[{"count":6,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/7803\/revisions"}],"predecessor-version":[{"id":8325,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/7803\/revisions\/8325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media\/7805"}],"wp:attachment":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media?parent=7803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/categories?post=7803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/tags?post=7803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}