{"id":8664,"date":"2024-12-04T10:49:00","date_gmt":"2024-12-04T08:49:00","guid":{"rendered":"https:\/\/www.lkjbw.de\/blog\/?p=8664"},"modified":"2025-02-03T15:40:59","modified_gmt":"2025-02-03T13:40:59","slug":"heimschule-st-landolin-ettenheim","status":"publish","type":"post","link":"https:\/\/www.lkjbw.de\/blog\/2024\/12\/heimschule-st-landolin-ettenheim\/","title":{"rendered":"Heimschule St. Landolin Ettenheim"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-medium\"><img loading=\"lazy\" width=\"300\" height=\"200\" src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/DSC_0003-300x200.jpg\" alt=\"zwei Jugendliche sind von hinten zu sehen, sie sitzen an einem Schultisch. Ein Jugendlicher h\u00e4lt ein Tablet, auf dem KI generierte Bilder zu sehen sind. Die beiden Jugendlichen schauen auf den Bildschirm. Auf dem Tisch steht ein weiteres Tablet.\" class=\"wp-image-8665 colorbox-8664\" srcset=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/DSC_0003-300x200.jpg 300w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/DSC_0003-1024x683.jpg 1024w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/DSC_0003-1536x1024.jpg 1536w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/DSC_0003-2048x1365.jpg 2048w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/DSC_0003-345x230.jpg 345w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/DSC_0003-250x167.jpg 250w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/DSC_0003-300x200@2x.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n<p>Am 03. und 04. Dezember 2024 fand das \u201eSmart Detectives\u201c-Projekt mit einer IT-spezialisierten 8. Klasse in Ettenheim statt. Der Workshop startete mit einer Einf\u00fchrung in die Passwortsicherheit, bei der die Sch\u00fcler*innen anhand eines Handys mit Sperrmuster schnell erkannten, wie unsichere Muster einfach entschl\u00fcsselt werden k\u00f6nnen. Im Anschluss durchst\u00f6berten sie das Handy, um Hinweise auf die fiktive Besitzerin zu finden. Sie entdeckten Rechnungen, Bilder und Belege und lernten, wie man aus solchen Informationen R\u00fcckschl\u00fcsse zieht.<\/p>\n\n\n\n<p>Das Thema \u201edigitaler Fu\u00dfabdruck\u201c folgte, wobei die Sch\u00fcler*innen ein gutes Vorwissen mitbrachten und intensiv dar\u00fcber diskutierten, wie ihre Daten im Internet genutzt werden. Sie pr\u00fcften, welche Daten von Apps gesammelt werden und wie sie die Privatsph\u00e4re besser sch\u00fctzen k\u00f6nnen. Ein kurzer Einblick in das Thema Cookies rundete das Thema ab.<\/p>\n\n\n\n<p>Am zweiten Tag lag der Fokus auf Bildrechten und K\u00fcnstlicher Intelligenz. Die Sch\u00fcler*innen erfuhren, wer das Recht hat, Bilder zu ver\u00f6ffentlichen, und experimentierten mit dem Tool \u201eCleanup.pictures\u201c, um Personen aus Fotos zu entfernen. Mit der Website \u201ewhichfaceisreal.com\u201c trainierten sie, KI-generierte Bilder zu erkennen, und erstellten eigene Bilder f\u00fcr den Instagram-Account der Handybesitzerin, wobei sie lernten, wie man gezielte Prompts formuliert. Ein weiterer Theorieblock zur KI-Verordnung der EU und das Erstellen von Deepfake-Videos rundeten das Projekt ab.<\/p>\n\n\n\n<p>In der abschlie\u00dfenden Reflexion wurde vor allem die praktische Arbeit von den Sch\u00fcler*innen gelobt. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/Urlaub-mit-meiner-Vespa-am-Strand.jpg\" alt=\"\" class=\"wp-image-8667 colorbox-8664\" srcset=\"https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/Urlaub-mit-meiner-Vespa-am-Strand.jpg 1024w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/Urlaub-mit-meiner-Vespa-am-Strand-150x150@2x.jpg 300w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/Urlaub-mit-meiner-Vespa-am-Strand-150x150.jpg 150w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/Urlaub-mit-meiner-Vespa-am-Strand-175x175.jpg 175w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/Urlaub-mit-meiner-Vespa-am-Strand-125x125.jpg 125w, https:\/\/www.lkjbw.de\/blog\/wp-content\/uploads\/2025\/01\/Urlaub-mit-meiner-Vespa-am-Strand-300x300@2x.jpg 600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 03. und 04. Dezember 2024 fand das \u201eSmart Detectives\u201c-Projekt mit einer IT-spezialisierten 8. Klasse in Ettenheim statt. Der Workshop startete mit einer Einf\u00fchrung in die Passwortsicherheit, bei der die Sch\u00fcler*innen anhand eines Handys mit Sperrmuster schnell erkannten, wie unsichere Muster einfach entschl\u00fcsselt werden k\u00f6nnen. Im Anschluss durchst\u00f6berten sie das Handy, um Hinweise auf die&#8230; <a class=\"moretag\" href=\"https:\/\/www.lkjbw.de\/blog\/2024\/12\/heimschule-st-landolin-ettenheim\/\"> weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":19,"featured_media":8665,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[45],"tags":[],"_links":{"self":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/8664"}],"collection":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/comments?post=8664"}],"version-history":[{"count":3,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/8664\/revisions"}],"predecessor-version":[{"id":8669,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/posts\/8664\/revisions\/8669"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media\/8665"}],"wp:attachment":[{"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/media?parent=8664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/categories?post=8664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lkjbw.de\/blog\/wp-json\/wp\/v2\/tags?post=8664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}